{"id":72796,"date":"2026-09-01T18:51:58","date_gmt":"2026-09-01T17:51:58","guid":{"rendered":"https:\/\/indykids.eu\/?post_type=product&#038;p=72796"},"modified":"2026-09-01T18:51:58","modified_gmt":"2026-09-01T17:51:58","slug":"trotinete-de-3-rodas-azul-safari-dreams-little-dutch","status":"publish","type":"product","link":"https:\/\/indykids.eu\/en\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/","title":{"rendered":"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch"},"content":{"rendered":"<table width=\"100%\">\n<tbody>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Nome da cor<\/td>\n<td class=\"w-4\/6 break-words\">azul<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">DESIGN<\/td>\n<td class=\"w-4\/6 break-words\">Maravilhas Do Safari<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Preenchimento<\/td>\n<td class=\"w-4\/6 break-words\">n\/a<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">R\u00f3tulo<\/td>\n<td class=\"w-4\/6 break-words\">n\/a<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Adequado para m\u00e1quina de lavar<\/td>\n<td class=\"w-4\/6 break-words\">N\u00e3o<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Material<\/td>\n<td class=\"w-4\/6 break-words\">Metal, Pl\u00e1stico<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Idade m\u00ednima<\/td>\n<td class=\"w-4\/6 break-words\">Mais de 3 anos<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">SKU<\/td>\n<td class=\"w-4\/6 break-words\">6085. azul<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Valor de Tog<\/td>\n<td class=\"w-4\/6 break-words\">n\/a<\/td>\n<\/tr>\n<tr>\n<td class=\"w-2\/6 break-words font-bold\">Foram instru\u00e7\u00f5es<\/td>\n<td class=\"w-4\/6 break-words\">n\/a<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>al\u00e7as marrons quentes transformam cada passeio em um pequeno momento de descoberta. Esteja seu filho andando pelo jardim, andando de scooter na cal\u00e7ada ou dando uma volta orgulhosa no parque, esta scooter convida voc\u00ea a se mover, descobrir e aproveitar estar ao ar livre. Gra\u00e7as \u00e0s duas rodas na frente e na traseira, a scooter \u00e9 resistente e est\u00e1vel. Isso d\u00e1 \u00e0s crian\u00e7as pequenas a partir dos 3 anos de idade confian\u00e7a extra enquanto andam de scooter. O guid\u00e3o \u00e9 ajust\u00e1vel em altura, para que a scooter cres\u00e7a confortavelmente e permane\u00e7a confort\u00e1vel de usar. H\u00e1 um freio acima da roda traseira, o que permite que seu filho diminua facilmente a velocidade enquanto joga. A scooter \u00e9 feita de metal e pl\u00e1stico e tem um tamanho de 56 x 23 x 78 cm. Para um visual completo, um capacete com estampa de saf\u00e1ri correspondente tamb\u00e9m est\u00e1 dispon\u00edvel, vendido separadamente.<\/p>\n","protected":false},"featured_media":72797,"template":"","meta":[],"product_cat":[109,7076,2196],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.9 (Yoast SEO v18.4.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trotinete de 3 rodas Azul Safari Dreams- Little Dutch - IndyKids - Baby &amp; Kids Goods<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch\" \/>\n<meta property=\"og:description\" content=\"al\u00e7as marrons quentes transformam cada passeio em um pequeno momento de descoberta. Esteja seu filho andando pelo jardim, andando de scooter na cal\u00e7ada ou dando uma volta orgulhosa no parque, esta scooter convida voc\u00ea a se mover, descobrir e aproveitar estar ao ar livre. Gra\u00e7as \u00e0s duas rodas na frente e na traseira, a scooter \u00e9 resistente e est\u00e1vel. Isso d\u00e1 \u00e0s crian\u00e7as pequenas a partir dos 3 anos de idade confian\u00e7a extra enquanto andam de scooter. O guid\u00e3o \u00e9 ajust\u00e1vel em altura, para que a scooter cres\u00e7a confortavelmente e permane\u00e7a confort\u00e1vel de usar. H\u00e1 um freio acima da roda traseira, o que permite que seu filho diminua facilmente a velocidade enquanto joga. A scooter \u00e9 feita de metal e pl\u00e1stico e tem um tamanho de 56 x 23 x 78 cm. Para um visual completo, um capacete com estampa de saf\u00e1ri correspondente tamb\u00e9m est\u00e1 dispon\u00edvel, vendido separadamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/\" \/>\n<meta property=\"og:site_name\" content=\"IndyKids - Baby &amp; Kids Goods\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/I.indykids.K\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"368\" \/>\n\t<meta property=\"og:image:height\" content=\"154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/indykids.eu\/#organization\",\"name\":\"IndyKids - Baby & Kids Goods\",\"url\":\"https:\/\/indykids.eu\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/I.indykids.K\/\",\"https:\/\/www.instagram.com\/indy.kids\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/indykids.eu\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png\",\"contentUrl\":\"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png\",\"width\":368,\"height\":154,\"caption\":\"IndyKids - Baby & Kids Goods\"},\"image\":{\"@id\":\"https:\/\/indykids.eu\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/indykids.eu\/#website\",\"url\":\"https:\/\/indykids.eu\/\",\"name\":\"IndyKids - Baby & Kids Goods\",\"description\":\"\\nShop for goods for babies and children. We have beautiful articles! Physical and online store. Here you can buy toys, furniture, decoration and textiles.\",\"publisher\":{\"@id\":\"https:\/\/indykids.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/indykids.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/indykids.eu\/wp-content\/uploads\/0034929_step-tricycle-blue-6085blue-product-10-shopify-square.jpg.webp\",\"contentUrl\":\"https:\/\/indykids.eu\/wp-content\/uploads\/0034929_step-tricycle-blue-6085blue-product-10-shopify-square.jpg.webp\",\"width\":960,\"height\":960},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#webpage\",\"url\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/\",\"name\":\"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch - IndyKids - Baby & Kids Goods\",\"isPartOf\":{\"@id\":\"https:\/\/indykids.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#primaryimage\"},\"datePublished\":\"2026-09-01T17:51:58+00:00\",\"dateModified\":\"2026-09-01T17:51:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\/\/indykids.eu\/en\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/indykids.eu\/en\/shop-en\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch\"}]}]}<\/script>\n<meta property=\"product:brand\" content=\"Little Dutch\" \/>\n<meta property=\"product:price:amount\" content=\"24.99\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch - IndyKids - Baby & Kids Goods","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/","og_locale":"en_US","og_type":"article","og_title":"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch","og_description":"al\u00e7as marrons quentes transformam cada passeio em um pequeno momento de descoberta. Esteja seu filho andando pelo jardim, andando de scooter na cal\u00e7ada ou dando uma volta orgulhosa no parque, esta scooter convida voc\u00ea a se mover, descobrir e aproveitar estar ao ar livre. Gra\u00e7as \u00e0s duas rodas na frente e na traseira, a scooter \u00e9 resistente e est\u00e1vel. Isso d\u00e1 \u00e0s crian\u00e7as pequenas a partir dos 3 anos de idade confian\u00e7a extra enquanto andam de scooter. O guid\u00e3o \u00e9 ajust\u00e1vel em altura, para que a scooter cres\u00e7a confortavelmente e permane\u00e7a confort\u00e1vel de usar. H\u00e1 um freio acima da roda traseira, o que permite que seu filho diminua facilmente a velocidade enquanto joga. A scooter \u00e9 feita de metal e pl\u00e1stico e tem um tamanho de 56 x 23 x 78 cm. Para um visual completo, um capacete com estampa de saf\u00e1ri correspondente tamb\u00e9m est\u00e1 dispon\u00edvel, vendido separadamente.","og_url":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/","og_site_name":"IndyKids - Baby & Kids Goods","article_publisher":"https:\/\/www.facebook.com\/I.indykids.K\/","og_image":[{"width":368,"height":154,"url":"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/indykids.eu\/#organization","name":"IndyKids - Baby & Kids Goods","url":"https:\/\/indykids.eu\/","sameAs":["https:\/\/www.facebook.com\/I.indykids.K\/","https:\/\/www.instagram.com\/indy.kids\/"],"logo":{"@type":"ImageObject","@id":"https:\/\/indykids.eu\/#logo","inLanguage":"en-US","url":"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png","contentUrl":"https:\/\/indykids.eu\/wp-content\/uploads\/2020\/10\/logo_indy.png","width":368,"height":154,"caption":"IndyKids - Baby & Kids Goods"},"image":{"@id":"https:\/\/indykids.eu\/#logo"}},{"@type":"WebSite","@id":"https:\/\/indykids.eu\/#website","url":"https:\/\/indykids.eu\/","name":"IndyKids - Baby & Kids Goods","description":"\nShop for goods for babies and children. We have beautiful articles! Physical and online store. Here you can buy toys, furniture, decoration and textiles.","publisher":{"@id":"https:\/\/indykids.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indykids.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#primaryimage","inLanguage":"en-US","url":"https:\/\/indykids.eu\/wp-content\/uploads\/0034929_step-tricycle-blue-6085blue-product-10-shopify-square.jpg.webp","contentUrl":"https:\/\/indykids.eu\/wp-content\/uploads\/0034929_step-tricycle-blue-6085blue-product-10-shopify-square.jpg.webp","width":960,"height":960},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#webpage","url":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/","name":"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch - IndyKids - Baby & Kids Goods","isPartOf":{"@id":"https:\/\/indykids.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#primaryimage"},"datePublished":"2026-09-01T17:51:58+00:00","dateModified":"2026-09-01T17:51:58+00:00","breadcrumb":{"@id":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/indykids.eu\/produto\/trotinete-de-3-rodas-azul-safari-dreams-little-dutch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/indykids.eu\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/indykids.eu\/en\/shop-en\/"},{"@type":"ListItem","position":3,"name":"Trotinete de 3 rodas Azul Safari Dreams- Little Dutch"}]}]},"product_brand":"Little Dutch","product_price_amount":"24.99","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/product\/72796"}],"collection":[{"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/media\/72797"}],"wp:attachment":[{"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/media?parent=72796"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/product_cat?post=72796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/indykids.eu\/en\/wp-json\/wp\/v2\/product_tag?post=72796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}